
{"id":31,"count":216,"description":"","link":"https:\/\/blog.polityka.pl\/polifonia\/category\/ocena\/910\/","name":"09\/10","slug":"910","taxonomy":"category","parent":98,"meta":[],"_links":{"self":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/categories\/31"}],"collection":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/categories\/98"}],"wp:post_type":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/posts?categories=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}