
{"id":1414,"count":1,"description":"","link":"https:\/\/blog.polityka.pl\/polifonia\/tag\/the-crystal-fighters\/","name":"The Crystal Fighters","slug":"the-crystal-fighters","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/tags\/1414"}],"collection":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.polityka.pl\/polifonia\/wp-json\/wp\/v2\/posts?tags=1414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}